{"id":3390,"date":"2020-05-15T04:04:54","date_gmt":"2020-05-15T04:04:54","guid":{"rendered":"http:\/\/pasajeros.com.co\/?page_id=3390"},"modified":"2021-05-27T17:30:18","modified_gmt":"2021-05-27T17:30:18","slug":"home","status":"publish","type":"page","link":"https:\/\/pasajeros.com.co\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<p>[vc_row simple_background_color=&#8221;#eeee22&#8243;][vc_column css=&#8221;.vc_custom_1589532544558{background-color: #120026 !important;}&#8221;][rev_slider_vc alias=&#8221;home-1-1&#8243; enable_paspartu=&#8221;no&#8221;][\/vc_column][\/vc_row][vc_row enable_skewed_section_effect=&#8221;yes&#8221; skewed_section_effect_top=&#8221;yes&#8221; skewed_section_effect_bottom=&#8221;yes&#8221; simple_background_color=&#8221;#000000&#8243;][vc_column][\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; content_text_aligment=&#8221;center&#8221; css=&#8221;.vc_custom_1607084599862{padding-top: 65px !important;padding-bottom: 65px !important;}&#8221; simple_background_color=&#8221;#000000&#8243;][vc_column][vc_row_inner content_text_aligment=&#8221;center&#8221;][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;4\/6&#8243;][vc_column_text css_animation=&#8221;fadeIn&#8221;]<\/p>\n<h4 style=\"text-align: center;\"><strong>Pasajeros<\/strong> is a video game that takes place through urban and surreal stories in a Chapinero taxi.<\/h4>\n<p>[\/vc_column_text][vc_empty_space]\n<a itemprop=\"url\" href=\"http:\/\/pasajeros.com.co\/descarga\/\" target=\"_self\"  class=\"edgtf-btn edgtf-btn-medium edgtf-btn-solid edgtf-btn-animation-3d edgtf-btn-animation-shadow\"  >\n    <span class=\"edgtf-btn-background-holder\"  ><\/span>\n    <span class=\"edgtf-btn-text\">Download<\/span>\n    <\/a>[\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row enable_skewed_section_effect=&#8221;yes&#8221; skewed_section_effect_bottom=&#8221;yes&#8221; simple_background_color=&#8221;#000000&#8243;][vc_column][\/vc_column][\/vc_row][vc_row video_bg=&#8221;yes&#8221; video_bg_url=&#8221;https:\/\/www.youtube.com\/watch?v=0c8KtclUgrA&#8221; content_text_aligment=&#8221;center&#8221; css=&#8221;.vc_custom_1618715483855{padding-top: 15.8% !important;padding-bottom: 17.3% !important;}&#8221;][vc_column video_bg=&#8221;yes&#8221; video_bg_url=&#8221;https:\/\/youtu.be\/0c8KtclUgrA&#8221;]<div class=\"edgtf-elements-holder   edgtf-one-column  edgtf-responsive-mode-768 \" ><div class=\"edgtf-eh-item    \"  data-item-class=\"edgtf-eh-custom-5241\" data-680=\"50px 100px\">\n\t<div class=\"edgtf-eh-item-inner\">\n\t\t<div class=\"edgtf-eh-item-content edgtf-eh-custom-5241\" >\n\t\t\t<div class=\"edgtf-video-button-holder  \">\n\t<div class=\"edgtf-video-button-image\">\n\t\t\t<\/div>\n\t\t\t<a class=\"edgtf-video-button-play-image \" href=\"https:\/\/youtu.be\/0c8KtclUgrA\" data-rel=\"prettyPhoto[video_button_pretty_photo_495]\">\n\t\t\t<span class=\"edgtf-video-button-play-inner\">\n\t\t\t\t<img width=\"170\" height=\"169\" src=\"https:\/\/pasajeros.com.co\/wp-content\/uploads\/2018\/08\/h2-video-button.png\" class=\"attachment-full size-full\" alt=\"i\" loading=\"lazy\" srcset=\"https:\/\/pasajeros.com.co\/wp-content\/uploads\/2018\/08\/h2-video-button.png 170w, https:\/\/pasajeros.com.co\/wp-content\/uploads\/2018\/08\/h2-video-button-150x150.png 150w, https:\/\/pasajeros.com.co\/wp-content\/uploads\/2018\/08\/h2-video-button-20x20.png 20w\" sizes=\"(max-width: 170px) 100vw, 170px\" \/>\t\t\t\t\t\t\t<\/span>\n\t\t<\/a>\n\t<\/div>[vc_column_text]<\/p>\n<h5>Click to watch the trailer<\/h5>\n<p>[\/vc_column_text]\t\t<\/div>\n\t<\/div>\n<\/div><\/div>[\/vc_column][\/vc_row][vc_row enable_skewed_section_effect=&#8221;yes&#8221; skewed_section_effect_top=&#8221;yes&#8221; simple_background_color=&#8221;#2f1250&#8243;][vc_column][\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; content_text_aligment=&#8221;center&#8221; css=&#8221;.vc_custom_1607084465294{padding-top: 20px !important;padding-bottom: 100px !important;}&#8221; simple_background_color=&#8221;#2f1250&#8243;][vc_column][vc_empty_space][vc_single_image image=&#8221;4521&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow_3d&#8221; el_class=&#8221;edgtf-glitch&#8221;]\n<a itemprop=\"url\" href=\"http:\/\/pasajeros.com.co\/descarga\/\" target=\"_self\"  class=\"edgtf-btn edgtf-btn-medium edgtf-btn-solid edgtf-btn-animation-3d edgtf-btn-animation-shadow\"  >\n    <span class=\"edgtf-btn-background-holder\"  ><\/span>\n    <span class=\"edgtf-btn-text\">Download<\/span>\n    <\/a>[\/vc_column][\/vc_row][vc_row enable_skewed_section_effect=&#8221;yes&#8221; skewed_section_effect_top=&#8221;yes&#8221; simple_background_color=&#8221;#000000&#8243;][vc_column][\/vc_column][\/vc_row][vc_row content_text_aligment=&#8221;center&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text css_animation=&#8221;fadeIn&#8221;]Subscribe to our mailing list to be aware of the news and updates of <strong>Pasajeros<\/strong>[\/vc_column_text][vc_raw_html]JTVCY29udGFjdC1mb3JtLTclMjBpZCUzRCUyMjM3NjMlMjIlMjB0aXRsZSUzRCUyMkJvbGV0aW4lMjIlNUQ=[\/vc_raw_html][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;64&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row simple_background_color=&#8221;#eeee22&#8243;][vc_column css=&#8221;.vc_custom_1589532544558{background-color: #120026 !important;}&#8221;][rev_slider_vc alias=&#8221;home-1-1&#8243; enable_paspartu=&#8221;no&#8221;][\/vc_column][\/vc_row][vc_row enable_skewed_section_effect=&#8221;yes&#8221; skewed_section_effect_top=&#8221;yes&#8221; skewed_section_effect_bottom=&#8221;yes&#8221; simple_background_color=&#8221;#000000&#8243;][vc_column][\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; content_text_aligment=&#8221;center&#8221; css=&#8221;.vc_custom_1607084599862{padding-top: 65px !important;padding-bottom: 65px !important;}&#8221; simple_background_color=&#8221;#000000&#8243;][vc_column][vc_row_inner content_text_aligment=&#8221;center&#8221;][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;4\/6&#8243;][vc_column_text css_animation=&#8221;fadeIn&#8221;] Pasajeros is a video game that takes place through urban and surreal stories in a Chapinero taxi. [\/vc_column_text][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row enable_skewed_section_effect=&#8221;yes&#8221; skewed_section_effect_bottom=&#8221;yes&#8221; simple_background_color=&#8221;#000000&#8243;][vc_column][\/vc_column][\/vc_row][vc_row video_bg=&#8221;yes&#8221; video_bg_url=&#8221;https:\/\/www.youtube.com\/watch?v=0c8KtclUgrA&#8221; content_text_aligment=&#8221;center&#8221; css=&#8221;.vc_custom_1618715483855{padding-top: 15.8% !important;padding-bottom: 17.3% !important;}&#8221;][vc_column video_bg=&#8221;yes&#8221; video_bg_url=&#8221;https:\/\/youtu.be\/0c8KtclUgrA&#8221;][\/vc_column][\/vc_row][vc_row enable_skewed_section_effect=&#8221;yes&#8221; skewed_section_effect_top=&#8221;yes&#8221; simple_background_color=&#8221;#2f1250&#8243;][vc_column][\/vc_column][\/vc_row][vc_row row_content_width=&#8221;grid&#8221; content_text_aligment=&#8221;center&#8221; css=&#8221;.vc_custom_1607084465294{padding-top: 20px !important;padding-bottom: 100px !important;}&#8221; simple_background_color=&#8221;#2f1250&#8243;][vc_column][vc_empty_space][vc_single_image image=&#8221;4521&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; style=&#8221;vc_box_shadow_3d&#8221; el_class=&#8221;edgtf-glitch&#8221;][\/vc_column][\/vc_row][vc_row enable_skewed_section_effect=&#8221;yes&#8221; skewed_section_effect_top=&#8221;yes&#8221; simple_background_color=&#8221;#000000&#8243;][vc_column][\/vc_column][\/vc_row][vc_row content_text_aligment=&#8221;center&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_empty_space][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_column_text css_animation=&#8221;fadeIn&#8221;]Subscribe to our [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Home - Pasajeros<\/title>\n<meta name=\"description\" content=\"\u201cPasajeros es un videojuego que se desarrolla por medio de una colecci\u00f3n de relatos urbanos y surreales recogidos en un taxi de chapinero. Es una aventura de cuatro noches cargada de microrrelatos de vampiros, robots, mariachis y matones. Adem\u00e1s de la oportunidad para encontrar el amor o la locura en la magia nocturna de una ciudad\u201d\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pasajeros.com.co\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Pasajeros\" \/>\n<meta property=\"og:description\" content=\"\u201cPasajeros es un videojuego que se desarrolla por medio de una colecci\u00f3n de relatos urbanos y surreales recogidos en un taxi de chapinero. Es una aventura de cuatro noches cargada de microrrelatos de vampiros, robots, mariachis y matones. Adem\u00e1s de la oportunidad para encontrar el amor o la locura en la magia nocturna de una ciudad\u201d\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pasajeros.com.co\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Pasajeros\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-27T17:30:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pasajeros.com.co\/en\/\",\"url\":\"https:\/\/pasajeros.com.co\/en\/\",\"name\":\"Home - Pasajeros\",\"isPartOf\":{\"@id\":\"https:\/\/pasajeros.com.co\/#website\"},\"datePublished\":\"2020-05-15T04:04:54+00:00\",\"dateModified\":\"2021-05-27T17:30:18+00:00\",\"description\":\"\u201cPasajeros es un videojuego que se desarrolla por medio de una colecci\u00f3n de relatos urbanos y surreales recogidos en un taxi de chapinero. Es una aventura de cuatro noches cargada de microrrelatos de vampiros, robots, mariachis y matones. Adem\u00e1s de la oportunidad para encontrar el amor o la locura en la magia nocturna de una ciudad\u201d\",\"breadcrumb\":{\"@id\":\"https:\/\/pasajeros.com.co\/en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pasajeros.com.co\/en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pasajeros.com.co\/en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/pasajeros.com.co\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pasajeros.com.co\/#website\",\"url\":\"https:\/\/pasajeros.com.co\/\",\"name\":\"Pasajeros\",\"description\":\"Pasajeros\",\"publisher\":{\"@id\":\"https:\/\/pasajeros.com.co\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pasajeros.com.co\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pasajeros.com.co\/#organization\",\"name\":\"Pasajeros\",\"url\":\"https:\/\/pasajeros.com.co\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/pasajeros.com.co\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/pasajeros.com.co\/wp-content\/uploads\/2020\/05\/logo_home-2.png\",\"contentUrl\":\"http:\/\/pasajeros.com.co\/wp-content\/uploads\/2020\/05\/logo_home-2.png\",\"width\":1200,\"height\":677,\"caption\":\"Pasajeros\"},\"image\":{\"@id\":\"https:\/\/pasajeros.com.co\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Pasajeros","description":"\u201cPasajeros es un videojuego que se desarrolla por medio de una colecci\u00f3n de relatos urbanos y surreales recogidos en un taxi de chapinero. Es una aventura de cuatro noches cargada de microrrelatos de vampiros, robots, mariachis y matones. Adem\u00e1s de la oportunidad para encontrar el amor o la locura en la magia nocturna de una ciudad\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pasajeros.com.co\/en\/","og_locale":"en_US","og_type":"article","og_title":"Home - Pasajeros","og_description":"\u201cPasajeros es un videojuego que se desarrolla por medio de una colecci\u00f3n de relatos urbanos y surreales recogidos en un taxi de chapinero. Es una aventura de cuatro noches cargada de microrrelatos de vampiros, robots, mariachis y matones. Adem\u00e1s de la oportunidad para encontrar el amor o la locura en la magia nocturna de una ciudad\u201d","og_url":"https:\/\/pasajeros.com.co\/en\/","og_site_name":"Pasajeros","article_modified_time":"2021-05-27T17:30:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pasajeros.com.co\/en\/","url":"https:\/\/pasajeros.com.co\/en\/","name":"Home - Pasajeros","isPartOf":{"@id":"https:\/\/pasajeros.com.co\/#website"},"datePublished":"2020-05-15T04:04:54+00:00","dateModified":"2021-05-27T17:30:18+00:00","description":"\u201cPasajeros es un videojuego que se desarrolla por medio de una colecci\u00f3n de relatos urbanos y surreales recogidos en un taxi de chapinero. Es una aventura de cuatro noches cargada de microrrelatos de vampiros, robots, mariachis y matones. Adem\u00e1s de la oportunidad para encontrar el amor o la locura en la magia nocturna de una ciudad\u201d","breadcrumb":{"@id":"https:\/\/pasajeros.com.co\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pasajeros.com.co\/en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pasajeros.com.co\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pasajeros.com.co\/en\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/pasajeros.com.co\/#website","url":"https:\/\/pasajeros.com.co\/","name":"Pasajeros","description":"Pasajeros","publisher":{"@id":"https:\/\/pasajeros.com.co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pasajeros.com.co\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pasajeros.com.co\/#organization","name":"Pasajeros","url":"https:\/\/pasajeros.com.co\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pasajeros.com.co\/#\/schema\/logo\/image\/","url":"http:\/\/pasajeros.com.co\/wp-content\/uploads\/2020\/05\/logo_home-2.png","contentUrl":"http:\/\/pasajeros.com.co\/wp-content\/uploads\/2020\/05\/logo_home-2.png","width":1200,"height":677,"caption":"Pasajeros"},"image":{"@id":"https:\/\/pasajeros.com.co\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/pasajeros.com.co\/en\/wp-json\/wp\/v2\/pages\/3390"}],"collection":[{"href":"https:\/\/pasajeros.com.co\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pasajeros.com.co\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pasajeros.com.co\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pasajeros.com.co\/en\/wp-json\/wp\/v2\/comments?post=3390"}],"version-history":[{"count":0,"href":"https:\/\/pasajeros.com.co\/en\/wp-json\/wp\/v2\/pages\/3390\/revisions"}],"wp:attachment":[{"href":"https:\/\/pasajeros.com.co\/en\/wp-json\/wp\/v2\/media?parent=3390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}